{"id":6269,"date":"2019-01-09T10:37:37","date_gmt":"2019-01-09T02:37:37","guid":{"rendered":"http:\/\/idsc.info\/web\/?page_id=6269"},"modified":"2019-01-09T10:37:43","modified_gmt":"2019-01-09T02:37:43","slug":"register","status":"publish","type":"page","link":"https:\/\/idsc.info\/web\/register\/","title":{"rendered":"Register"},"content":{"rendered":"\n<div id=\"wpmem_reg\"><a id=\"register\"><\/a><form name=\"form\" method=\"post\" action=\"https:\/\/idsc.info\/web\/register\/\" id=\"wpmem_register_form\" class=\"form\"><input type=\"hidden\" id=\"_wpmem_register_nonce\" name=\"_wpmem_register_nonce\" value=\"9f535ffb4e\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/web\/wp-json\/wp\/v2\/pages\/6269\" \/><fieldset><legend>New User Registration<\/legend><label for=\"username\" class=\"text\">Choose a Username<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"username\" type=\"text\" id=\"username\" value=\"\" class=\"textbox\" required  \/><\/div><label for=\"password\" class=\"text\">Password<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"password\" type=\"password\" id=\"password\" class=\"textbox\" required  \/><\/div><label for=\"confirm_password\" class=\"text\">Confirm Password<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"confirm_password\" type=\"password\" id=\"confirm_password\" class=\"textbox\" required  \/><\/div><label for=\"company\" class=\"text\">Company Name<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"company\" type=\"text\" id=\"company\" value=\"\" class=\"textbox\" required  \/><\/div><label for=\"first_name\" class=\"text\">First Name<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"first_name\" type=\"text\" id=\"first_name\" value=\"\" class=\"textbox\" required  \/><\/div><label for=\"last_name\" class=\"text\">Last Name<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"last_name\" type=\"text\" id=\"last_name\" value=\"\" class=\"textbox\" required  \/><\/div><label for=\"billing_address_1\" class=\"text\">Address 1<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"billing_address_1\" type=\"text\" id=\"billing_address_1\" value=\"\" class=\"textbox\" required  \/><\/div><label for=\"billing_address_2\" class=\"text\">Address 2<\/label><div class=\"div_text\"><input name=\"billing_address_2\" type=\"text\" id=\"billing_address_2\" value=\"\" class=\"textbox\" \/><\/div><label for=\"billing_city\" class=\"text\">City<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"billing_city\" type=\"text\" id=\"billing_city\" value=\"\" class=\"textbox\" required  \/><\/div><label for=\"billing_state\" class=\"text\">State<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"billing_state\" type=\"text\" id=\"billing_state\" value=\"\" class=\"textbox\" required  \/><\/div><label for=\"billing_postcode\" class=\"text\">Zip<\/label><div class=\"div_text\"><input name=\"billing_postcode\" type=\"text\" id=\"billing_postcode\" value=\"\" class=\"textbox\" \/><\/div><label for=\"billing_country\" class=\"text\">Country<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"billing_country\" type=\"text\" id=\"billing_country\" value=\"\" class=\"textbox\" required  \/><\/div><label for=\"billing_phone\" class=\"text\">Phone<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"billing_phone\" type=\"text\" id=\"billing_phone\" value=\"\" class=\"textbox\" required  \/><\/div><label for=\"user_email\" class=\"text\">Email<span class=\"req\">*<\/span><\/label><div class=\"div_text\"><input name=\"user_email\" type=\"email\" id=\"user_email\" value=\"\" class=\"textbox\" required  \/><\/div><input name=\"a\" type=\"hidden\" value=\"register\" \/><input name=\"wpmem_reg_page\" type=\"hidden\" value=\"https:\/\/idsc.info\/web\/register\/\" \/><div class=\"button_div\"><input name=\"submit\" type=\"submit\" value=\"Register\" class=\"buttons\" \/><\/div><div class=\"req-text\"><span class=\"req\">*<\/span>Required field<\/div><\/fieldset><\/form><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/idsc.info\/web\/wp-json\/wp\/v2\/pages\/6269"}],"collection":[{"href":"https:\/\/idsc.info\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/idsc.info\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/idsc.info\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/idsc.info\/web\/wp-json\/wp\/v2\/comments?post=6269"}],"version-history":[{"count":2,"href":"https:\/\/idsc.info\/web\/wp-json\/wp\/v2\/pages\/6269\/revisions"}],"predecessor-version":[{"id":6271,"href":"https:\/\/idsc.info\/web\/wp-json\/wp\/v2\/pages\/6269\/revisions\/6271"}],"wp:attachment":[{"href":"https:\/\/idsc.info\/web\/wp-json\/wp\/v2\/media?parent=6269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}